{"id":98,"date":"2023-03-12T14:26:47","date_gmt":"2023-03-12T14:26:47","guid":{"rendered":"https:\/\/sorte6.com\/blog\/?page_id=98"},"modified":"2023-03-12T14:26:47","modified_gmt":"2023-03-12T14:26:47","slug":"politica-de-privacidade-uso-de-cookies","status":"publish","type":"page","link":"https:\/\/sorte6.com\/blog\/politica-de-privacidade-uso-de-cookies\/","title":{"rendered":"Pol\u00edtica de Privacidade &#038; Uso de Cookies"},"content":{"rendered":"<h2><span style=\"color: #444444;\">Pol&iacute;tica Privacidade<\/span><p><span style=\"color: #444444;\">A sua privacidade &eacute; importante para n&oacute;s. &Eacute; pol&iacute;tica do Sorte6.com respeitar a sua privacidade em rela&ccedil;&atilde;o a qualquer informa&ccedil;&atilde;o sua que possamos coletar no site <a href=\"https:\/\/sorte6.com\/blog\">Sorte6.com<\/a>, e outros sites que possu&iacute;mos e operamos.<\/span><\/p><p><span style=\"color: #444444;\">Solicitamos informa&ccedil;&otilde;es pessoais apenas quando realmente precisamos delas para lhe fornecer um servi&ccedil;o. Fazemo-lo por meios justos e legais, com o seu conhecimento e consentimento. Tamb&eacute;m informamos por que estamos coletando e como ser&aacute; usado.<\/span><\/p><p><span style=\"color: #444444;\">Apenas retemos as informa&ccedil;&otilde;es coletadas pelo tempo necess&aacute;rio para fornecer o servi&ccedil;o solicitado. Quando armazenamos dados, protegemos dentro de meios comercialmente aceit&aacute;veis &#8203;&#8203;para evitar perdas e roubos, bem como acesso, divulga&ccedil;&atilde;o, c&oacute;pia, uso ou modifica&ccedil;&atilde;o n&atilde;o autorizados.<\/span><\/p><p><span style=\"color: #444444;\">N&atilde;o compartilhamos informa&ccedil;&otilde;es de identifica&ccedil;&atilde;o pessoal publicamente ou com terceiros, exceto quando exigido por lei.<\/span><\/p><p><span style=\"color: #444444;\">O nosso site pode ter links para sites externos que n&atilde;o s&atilde;o operados por n&oacute;s. Esteja ciente de que n&atilde;o temos controle sobre o conte&uacute;do e pr&aacute;ticas desses sites e n&atilde;o podemos aceitar responsabilidade por suas respectivas&nbsp;<\/span>pol&iacute;ticas de privacidade<span style=\"color: #444444;\">.<\/span><\/p><p><span style=\"color: #444444;\">Voc&ecirc; &eacute; livre para recusar a nossa solicita&ccedil;&atilde;o de informa&ccedil;&otilde;es pessoais, entendendo que talvez n&atilde;o possamos fornecer alguns dos servi&ccedil;os desejados.<\/span><\/p><p><span style=\"color: #444444;\">O uso continuado de nosso site ser&aacute; considerado como aceita&ccedil;&atilde;o de nossas pr&aacute;ticas em torno de privacidade e informa&ccedil;&otilde;es pessoais. Se voc&ecirc; tiver alguma d&uacute;vida sobre como lidamos com dados do usu&aacute;rio e informa&ccedil;&otilde;es pessoais, entre em contato conosco.<\/span><\/p><p>&nbsp;<\/p><ul>\n<li><span style=\"color: #444444;\">O servi&ccedil;o Google AdSense que usamos para veicular publicidade usa um cookie DoubleClick para veicular an&uacute;ncios mais relevantes em toda a Web e limitar o n&uacute;mero de vezes que um determinado an&uacute;ncio &eacute; exibido para voc&ecirc;.<\/span><\/li>\n<li><span style=\"color: #444444;\">Para mais informa&ccedil;&otilde;es sobre o Google AdSense, consulte as FAQs oficiais sobre privacidade do Google AdSense.<\/span><\/li>\n<li><span style=\"color: #444444;\">Utilizamos an&uacute;ncios para compensar os custos de funcionamento deste site e fornecer financiamento para futuros desenvolvimentos. Os cookies de publicidade comportamental usados &#8203;&#8203;por este site foram projetados para garantir que voc&ecirc; forne&ccedil;a os an&uacute;ncios mais relevantes sempre que poss&iacute;vel, rastreando anonimamente seus interesses e apresentando coisas semelhantes que possam ser do seu interesse.<\/span><\/li>\n<li><span style=\"color: #444444;\">V&aacute;rios parceiros anunciam em nosso nome e os cookies de rastreamento de afiliados simplesmente nos permitem ver se nossos clientes acessaram o site atrav&eacute;s de um dos sites de nossos parceiros, para que possamos credit&aacute;-los adequadamente e, quando aplic&aacute;vel, permitir que nossos parceiros afiliados ofere&ccedil;am qualquer promo&ccedil;&atilde;o que pode fornec&ecirc;-lo para fazer uma compra.<\/span><\/li>\n<\/ul><h3><span style=\"color: #444444;\">Compromisso do Usu&aacute;rio<\/span><\/h3><p><span style=\"color: #444444;\">O usu&aacute;rio se compromete a fazer uso adequado dos conte&uacute;dos e da informa&ccedil;&atilde;o que o Sorte6.com oferece no site e com car&aacute;ter enunciativo, mas n&atilde;o limitativo:<\/span><\/p><ul>\n<li><span style=\"color: #444444;\">A) N&atilde;o se envolver em atividades que sejam ilegais ou contr&aacute;rias &agrave; boa f&eacute; a &agrave; ordem p&uacute;blica;<\/span><\/li>\n<li><span style=\"color: #444444;\">B) N&atilde;o difundir propaganda ou conte&uacute;do de natureza racista, xenof&oacute;bica, <\/span><span style=\"color: #212529;\"><span style=\"color: #444444;\"> ou azar, qualquer tipo de pornografia ilegal, de apologia ao terrorismo ou contra os direitos humanos;<\/span><\/span><\/li>\n<li><span style=\"color: #444444;\">C) N&atilde;o causar danos aos sistemas f&iacute;sicos (hardwares) e l&oacute;gicos (softwares) do Sorte6.com, de seus fornecedores ou terceiros, para introduzir ou disseminar v&iacute;rus inform&aacute;ticos ou quaisquer outros sistemas de hardware ou software que sejam capazes de causar danos anteriormente mencionados.<\/span><\/li>\n<\/ul><h3><span style=\"color: #444444;\">Mais informa&ccedil;&otilde;es<\/span><\/h3><p><span style=\"color: #444444;\">Esperemos que esteja esclarecido e, como mencionado anteriormente, se houver algo que voc&ecirc; n&atilde;o tem certeza se precisa ou n&atilde;o, geralmente &eacute; mais seguro deixar os cookies ativados, caso interaja com um dos recursos que voc&ecirc; usa em nosso site.<\/span><\/p><p><span style=\"color: #444444;\">Esta pol&iacute;tica &eacute; efetiva a partir de 12 de mar&ccedil;o de 2023.<\/span><\/p><\/h2>\n","protected":false},"excerpt":{"rendered":"<p>Pol&iacute;tica PrivacidadeA sua privacidade &eacute; importante para n&oacute;s. &Eacute; pol&iacute;tica do Sorte6.com respeitar a sua privacidade em rela&ccedil;&atilde;o a qualquer informa&ccedil;&atilde;o sua que possamos coletar no site Sorte6.com, e outros sites que possu&iacute;mos e operamos.Solicitamos informa&ccedil;&otilde;es pessoais apenas quando realmente precisamos delas para lhe fornecer um servi&ccedil;o. Fazemo-lo por meios justos e legais, com o&hellip;&nbsp;<a href=\"https:\/\/sorte6.com\/blog\/politica-de-privacidade-uso-de-cookies\/\" rel=\"bookmark\">Continue a ler &raquo;<span class=\"screen-reader-text\">Pol\u00edtica de Privacidade &#038; Uso de Cookies<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"off","neve_meta_content_width":100,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"","footnotes":""},"class_list":["post-98","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/sorte6.com\/blog\/wp-json\/wp\/v2\/pages\/98","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sorte6.com\/blog\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sorte6.com\/blog\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sorte6.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sorte6.com\/blog\/wp-json\/wp\/v2\/comments?post=98"}],"version-history":[{"count":1,"href":"https:\/\/sorte6.com\/blog\/wp-json\/wp\/v2\/pages\/98\/revisions"}],"predecessor-version":[{"id":99,"href":"https:\/\/sorte6.com\/blog\/wp-json\/wp\/v2\/pages\/98\/revisions\/99"}],"wp:attachment":[{"href":"https:\/\/sorte6.com\/blog\/wp-json\/wp\/v2\/media?parent=98"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}